{"id":4025,"date":"2014-05-03T13:50:37","date_gmt":"2014-05-03T11:50:37","guid":{"rendered":"https:\/\/www.maderasmenur.com\/?p=4025"},"modified":"2019-12-05T16:25:24","modified_gmt":"2019-12-05T15:25:24","slug":"certificado-aeim","status":"publish","type":"post","link":"https:\/\/www.maderasmenur.com\/it\/certificado-aeim\/","title":{"rendered":"Certificado AEIM"},"content":{"rendered":"<p style=\"text-align: center;\">Maderas Menur es miembro de la Asociaci\u00f3n Espa\u00f1ola del Comercio e Industria de la Madera (AEIM).<\/p>\n<p style=\"text-align: center;\">Hemos conseguido un nuevo certificado que es otorgado a las empresas que comercializan en el mercado de la Uni\u00f3nEuropea, madera y productos de la madera, es el llamado I.D.D. (Sistema de Diligencia Debida).<\/p>\n<p style=\"text-align: center;\">Con este certificado seguimos abriendonos puestas tanto a niverl nacional o como a nivel Europeo.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.maderasmenur.com\/wp-content\/uploads\/aeim.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4026\" src=\"https:\/\/www.maderasmenur.com\/wp-content\/uploads\/aeim.jpg\" alt=\"aeim\" width=\"597\" height=\"627\" srcset=\"https:\/\/www.maderasmenur.com\/wp-content\/uploads\/aeim.jpg 597w, https:\/\/www.maderasmenur.com\/wp-content\/uploads\/aeim-286x300.jpg 286w, https:\/\/www.maderasmenur.com\/wp-content\/uploads\/aeim-450x472.jpg 450w, https:\/\/www.maderasmenur.com\/wp-content\/uploads\/aeim-20x20.jpg 20w, https:\/\/www.maderasmenur.com\/wp-content\/uploads\/aeim-285x300.jpg 285w\" sizes=\"auto, (max-width: 597px) 100vw, 597px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maderas Menur es miembro de la Asociaci\u00f3n Espa\u00f1ola del Comercio e Industria de la Madera (AEIM). Hemos conseguido un nuevo certificado que es otorgado a las empresas que comercializan en el mercado de la Uni\u00f3nEuropea, madera y productos de la madera, es el llamado I.D.D. (Sistema de Diligencia Debida). Con este certificado seguimos abriendonos puestas [&hellip;]<\/p>\n","protected":false},"author":1001093,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-4025","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.maderasmenur.com\/it\/wp-json\/wp\/v2\/posts\/4025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maderasmenur.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.maderasmenur.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.maderasmenur.com\/it\/wp-json\/wp\/v2\/users\/1001093"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maderasmenur.com\/it\/wp-json\/wp\/v2\/comments?post=4025"}],"version-history":[{"count":0,"href":"https:\/\/www.maderasmenur.com\/it\/wp-json\/wp\/v2\/posts\/4025\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.maderasmenur.com\/it\/wp-json\/wp\/v2\/media?parent=4025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.maderasmenur.com\/it\/wp-json\/wp\/v2\/categories?post=4025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.maderasmenur.com\/it\/wp-json\/wp\/v2\/tags?post=4025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}